{"id":15863,"date":"2017-05-31T17:59:44","date_gmt":"2017-05-31T15:59:44","guid":{"rendered":"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/15863\/?post_type=wpbdp_listing&#038;p=15863"},"modified":"2017-05-31T17:59:44","modified_gmt":"2017-05-31T15:59:44","slug":"histoire-de-chateau-du-loir-sarthe","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/","title":{"rendered":"Histoire de Ch\u00e2teau du Loir (Sarthe)"},"content":{"rendered":"<p>Aux confins de l&rsquo;Anjou historique, et du Maine, Ch\u00e2teau-du-Loir est situ\u00e9 aux limites du pays du Maine angevin, pr\u00e8s de la Touraine. La situation g\u00e9ographique privil\u00e9gi\u00e9e du canton attira de nombreuses convoitises tout au long de l&rsquo;histoire. Les rois de France et d&rsquo;Angleterre se disput\u00e8rent cette place forte, chef-lieu d&rsquo;une s\u00e9n\u00e9chauss\u00e9e de 78 paroisses (doyenn\u00e9 rattach\u00e9 au dioc\u00e8se du Mans), jusqu&rsquo;en 1789&#8230;<br \/>\n(source wikipedia)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aux confins de l&rsquo;Anjou historique, et du Maine, Ch\u00e2teau-du-Loir est situ\u00e9 aux limites du pays du Maine angevin, pr\u00e8s de la Touraine. La situation g\u00e9ographique privil\u00e9gi\u00e9e du canton attira de nombreuses convoitises tout au long de l&rsquo;histoire. Les rois de &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[28],"wpbdp_tag":[],"class_list":["post-15863","wpbdp_listing","type-wpbdp_listing","status-publish","hentry","wpbdp_category-72-sarthe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Ch\u00e2teau du Loir (Sarthe) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Ch\u00e2teau du Loir (Sarthe) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"Aux confins de l&rsquo;Anjou historique, et du Maine, Ch\u00e2teau-du-Loir est situ\u00e9 aux limites du pays du Maine angevin, pr\u00e8s de la Touraine. La situation g\u00e9ographique privil\u00e9gi\u00e9e du canton attira de nombreuses convoitises tout au long de l&rsquo;histoire. Les rois de &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-chateau-du-loir-sarthe\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-chateau-du-loir-sarthe\\\/\",\"name\":\"Histoire de Ch\u00e2teau du Loir (Sarthe) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"datePublished\":\"2017-05-31T15:59:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-chateau-du-loir-sarthe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-chateau-du-loir-sarthe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-chateau-du-loir-sarthe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Ch\u00e2teau du Loir (Sarthe)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Ch\u00e2teau du Loir (Sarthe) - Annuaire Historique des Communes de France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Ch\u00e2teau du Loir (Sarthe) - Annuaire Historique des Communes de France","og_description":"Aux confins de l&rsquo;Anjou historique, et du Maine, Ch\u00e2teau-du-Loir est situ\u00e9 aux limites du pays du Maine angevin, pr\u00e8s de la Touraine. La situation g\u00e9ographique privil\u00e9gi\u00e9e du canton attira de nombreuses convoitises tout au long de l&rsquo;histoire. Les rois de &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/","name":"Histoire de Ch\u00e2teau du Loir (Sarthe) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"datePublished":"2017-05-31T15:59:44+00:00","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-chateau-du-loir-sarthe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire de Ch\u00e2teau du Loir (Sarthe)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/15863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=15863"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=15863"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=15863"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=15863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}