{"id":22346,"date":"2017-12-27T16:32:52","date_gmt":"2017-12-27T15:32:52","guid":{"rendered":"http:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/22346\/?post_type=wpbdp_listing&#038;p=22346"},"modified":"2017-12-27T16:36:06","modified_gmt":"2017-12-27T15:36:06","slug":"histoire-de-conge-sur-orne-sarthe","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/","title":{"rendered":"Histoire de Cong\u00e9 sur Orne (Sarthe)"},"content":{"rendered":"<ul>\n<li>La localit\u00e9 est appel\u00e9e <i>Cong\u00e9<\/i> puis <i>Cong\u00e9-sur-Orne<\/i> \u00e0 partir de 1801.<\/li>\n<li>Dans son dictionnaire topographique publi\u00e9 en 1829, Julien R\u00e9my Pesche propose l&rsquo;origine suivante\u00a0: de <i>Congestio<\/i> ou <i>Congestus<\/i>, c&rsquo;est-\u00e0-dire amas, assemblage, soit de la terre et de la vase charri\u00e9es par les eaux de la rivi\u00e8re <a title=\"Orne saosnoise\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Orne_saosnoise\">Orne saosnoise<\/a>, soit les eaux d\u00e9bord\u00e9es elles-m\u00eames qui croupissent sur un terrain argileux&#8230;<\/li>\n<\/ul>\n<p>(source wikipedia&#8230; lire la suite)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La localit\u00e9 est appel\u00e9e Cong\u00e9 puis Cong\u00e9-sur-Orne \u00e0 partir de 1801. Dans son dictionnaire topographique publi\u00e9 en 1829, Julien R\u00e9my Pesche propose l&rsquo;origine suivante\u00a0: de Congestio ou Congestus, c&rsquo;est-\u00e0-dire amas, assemblage, soit de la terre et de la vase charri\u00e9es &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[28],"wpbdp_tag":[],"class_list":["post-22346","wpbdp_listing","type-wpbdp_listing","status-publish","hentry","wpbdp_category-72-sarthe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Cong\u00e9 sur Orne (Sarthe) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Cong\u00e9 sur Orne (Sarthe) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"La localit\u00e9 est appel\u00e9e Cong\u00e9 puis Cong\u00e9-sur-Orne \u00e0 partir de 1801. Dans son dictionnaire topographique publi\u00e9 en 1829, Julien R\u00e9my Pesche propose l&rsquo;origine suivante\u00a0: de Congestio ou Congestus, c&rsquo;est-\u00e0-dire amas, assemblage, soit de la terre et de la vase charri\u00e9es &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-27T15:36:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-conge-sur-orne-sarthe\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-conge-sur-orne-sarthe\\\/\",\"name\":\"Histoire de Cong\u00e9 sur Orne (Sarthe) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"datePublished\":\"2017-12-27T15:32:52+00:00\",\"dateModified\":\"2017-12-27T15:36:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-conge-sur-orne-sarthe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-conge-sur-orne-sarthe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-conge-sur-orne-sarthe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Cong\u00e9 sur Orne (Sarthe)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Cong\u00e9 sur Orne (Sarthe) - Annuaire Historique des Communes de France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Cong\u00e9 sur Orne (Sarthe) - Annuaire Historique des Communes de France","og_description":"La localit\u00e9 est appel\u00e9e Cong\u00e9 puis Cong\u00e9-sur-Orne \u00e0 partir de 1801. Dans son dictionnaire topographique publi\u00e9 en 1829, Julien R\u00e9my Pesche propose l&rsquo;origine suivante\u00a0: de Congestio ou Congestus, c&rsquo;est-\u00e0-dire amas, assemblage, soit de la terre et de la vase charri\u00e9es &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","article_modified_time":"2017-12-27T15:36:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/","name":"Histoire de Cong\u00e9 sur Orne (Sarthe) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"datePublished":"2017-12-27T15:32:52+00:00","dateModified":"2017-12-27T15:36:06+00:00","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-conge-sur-orne-sarthe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire de Cong\u00e9 sur Orne (Sarthe)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/22346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=22346"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=22346"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=22346"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=22346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}