{"id":34188,"date":"2020-06-09T14:28:22","date_gmt":"2020-06-09T12:28:22","guid":{"rendered":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?post_type=wpbdp_listing&#038;p=34188"},"modified":"2020-06-09T14:28:22","modified_gmt":"2020-06-09T12:28:22","slug":"histoire-de-longecourt-en-plaine-cote-dor-2","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/","title":{"rendered":"Histoire de Longecourt en Plaine (C\u00f4te d&rsquo;Or)"},"content":{"rendered":"<p>L&rsquo;histoire du village de Longecourt-en-Plaine est tr\u00e8s li\u00e9e \u00e0 celle de la seigneurie de Longecourt et de son <a title=\"Ch\u00e2teau de Longecourt-en-Plaine\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Ch%C3%A2teau_de_Longecourt-en-Plaine\">ch\u00e2teau<\/a>, notamment pour la p\u00e9riode d&rsquo;Ancien R\u00e9gime.<br \/>\nLa seigneurie de Longecourt est cit\u00e9e d\u00e8s le <abbr class=\"abbr\" title=\"13\u1d49 si\u00e8cle\"><span class=\"romain\">XIII<\/span><sup>e<\/sup><\/abbr>\u00a0si\u00e8cle. Le domaine appartient alors \u00e0 Robert de Boisleux<sup id=\"cite_ref-2\" class=\"reference\"><\/sup>, seigneur d&rsquo;origine <a title=\"Artois\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Artois\">art\u00e9sienne<\/a> qui vit dans l&rsquo;entourage du <a title=\"Liste des ducs de Bourgogne\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Liste_des_ducs_de_Bourgogne\">duc de Bourgogne<\/a>. Une premi\u00e8re maison forte de plaine, avec foss\u00e9s et pont-levis, est construite sur les fondations d&rsquo;une ancienne motte f\u00e9odale&#8230;<\/p>\n<p>(source wikipedia&#8230; lire la suite)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;histoire du village de Longecourt-en-Plaine est tr\u00e8s li\u00e9e \u00e0 celle de la seigneurie de Longecourt et de son ch\u00e2teau, notamment pour la p\u00e9riode d&rsquo;Ancien R\u00e9gime. La seigneurie de Longecourt est cit\u00e9e d\u00e8s le XIIIe\u00a0si\u00e8cle. Le domaine appartient alors \u00e0 Robert &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":34189,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[67],"wpbdp_tag":[],"class_list":["post-34188","wpbdp_listing","type-wpbdp_listing","status-publish","has-post-thumbnail","hentry","wpbdp_category-21-cote-dor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Longecourt en Plaine (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Longecourt en Plaine (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;histoire du village de Longecourt-en-Plaine est tr\u00e8s li\u00e9e \u00e0 celle de la seigneurie de Longecourt et de son ch\u00e2teau, notamment pour la p\u00e9riode d&rsquo;Ancien R\u00e9gime. La seigneurie de Longecourt est cit\u00e9e d\u00e8s le XIIIe\u00a0si\u00e8cle. Le domaine appartient alors \u00e0 Robert &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"og:image\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/06\/longecourtenplaine21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/\",\"name\":\"Histoire de Longecourt en Plaine (C\u00f4te d'Or) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/longecourtenplaine21.jpg\",\"datePublished\":\"2020-06-09T12:28:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/longecourtenplaine21.jpg\",\"contentUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/longecourtenplaine21.jpg\",\"width\":280,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-longecourt-en-plaine-cote-dor-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Longecourt en Plaine (C\u00f4te d&rsquo;Or)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Longecourt en Plaine (C\u00f4te d'Or) - Annuaire Historique des Communes de France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Longecourt en Plaine (C\u00f4te d'Or) - Annuaire Historique des Communes de France","og_description":"L&rsquo;histoire du village de Longecourt-en-Plaine est tr\u00e8s li\u00e9e \u00e0 celle de la seigneurie de Longecourt et de son ch\u00e2teau, notamment pour la p\u00e9riode d&rsquo;Ancien R\u00e9gime. La seigneurie de Longecourt est cit\u00e9e d\u00e8s le XIIIe\u00a0si\u00e8cle. Le domaine appartient alors \u00e0 Robert &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","og_image":[{"width":280,"height":168,"url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/06\/longecourtenplaine21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/","name":"Histoire de Longecourt en Plaine (C\u00f4te d'Or) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/#primaryimage"},"image":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/#primaryimage"},"thumbnailUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/06\/longecourtenplaine21.jpg","datePublished":"2020-06-09T12:28:22+00:00","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/#primaryimage","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/06\/longecourtenplaine21.jpg","contentUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/06\/longecourtenplaine21.jpg","width":280,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-longecourt-en-plaine-cote-dor-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire de Longecourt en Plaine (C\u00f4te d&rsquo;Or)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/34188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=34188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media\/34189"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=34188"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=34188"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=34188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}