{"id":34685,"date":"2020-08-23T20:29:08","date_gmt":"2020-08-23T18:29:08","guid":{"rendered":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?post_type=wpbdp_listing&#038;p=34685"},"modified":"2020-08-23T20:29:08","modified_gmt":"2020-08-23T18:29:08","slug":"histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/","title":{"rendered":"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d&rsquo;Or)"},"content":{"rendered":"<p>Par sa position isol\u00e9e et dominante, la situation du Mont de Marcilly avait tout naturellement s\u00e9duit les hommes du N\u00e9olithique. En effet, il permettait le contr\u00f4le de la vall\u00e9e de la Tille. Ce poste d&rsquo;observation servait \u00e9galement de refuge en cas de danger. Des armes (lames de faucilles et de couteaux), des outils nettement sp\u00e9cialis\u00e9s (scie)&#8230; y ont \u00e9t\u00e9 retrouv\u00e9s et sont expos\u00e9s au Mus\u00e9e Arch\u00e9ologique de Dijon&#8230;<\/p>\n<p>(image et extrait du site officiel de la commune&#8230; lire la suite)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Par sa position isol\u00e9e et dominante, la situation du Mont de Marcilly avait tout naturellement s\u00e9duit les hommes du N\u00e9olithique. En effet, il permettait le contr\u00f4le de la vall\u00e9e de la Tille. Ce poste d&rsquo;observation servait \u00e9galement de refuge en &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":34686,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[67],"wpbdp_tag":[],"class_list":["post-34685","wpbdp_listing","type-wpbdp_listing","status-publish","has-post-thumbnail","hentry","wpbdp_category-21-cote-dor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"Par sa position isol\u00e9e et dominante, la situation du Mont de Marcilly avait tout naturellement s\u00e9duit les hommes du N\u00e9olithique. En effet, il permettait le contr\u00f4le de la vall\u00e9e de la Tille. Ce poste d&rsquo;observation servait \u00e9galement de refuge en &hellip; Continuer la lecture &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"og:image\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/08\/marcillysurtille21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"336\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/\",\"name\":\"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d'Or) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/marcillysurtille21.jpg\",\"datePublished\":\"2020-08-23T18:29:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/marcillysurtille21.jpg\",\"contentUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/marcillysurtille21.jpg\",\"width\":336,\"height\":448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d&rsquo;Or)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d'Or) - Annuaire Historique des Communes de France","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d'Or) - Annuaire Historique des Communes de France","og_description":"Par sa position isol\u00e9e et dominante, la situation du Mont de Marcilly avait tout naturellement s\u00e9duit les hommes du N\u00e9olithique. En effet, il permettait le contr\u00f4le de la vall\u00e9e de la Tille. Ce poste d&rsquo;observation servait \u00e9galement de refuge en &hellip; Continuer la lecture &rarr;","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","og_image":[{"width":336,"height":448,"url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/08\/marcillysurtille21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/","name":"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d'Or) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/#primaryimage"},"image":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/#primaryimage"},"thumbnailUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/08\/marcillysurtille21.jpg","datePublished":"2020-08-23T18:29:08+00:00","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/#primaryimage","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/08\/marcillysurtille21.jpg","contentUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2020\/08\/marcillysurtille21.jpg","width":336,"height":448},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-marcilly-sur-tille-cote-dor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Marcilly sur Tille (C\u00f4te d&rsquo;Or)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/34685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=34685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media\/34686"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=34685"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=34685"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=34685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}