{"id":41974,"date":"2022-01-27T14:00:39","date_gmt":"2022-01-27T13:00:39","guid":{"rendered":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?post_type=wpbdp_listing&#038;p=41974"},"modified":"2022-01-27T14:00:39","modified_gmt":"2022-01-27T13:00:39","slug":"histoire-de-buffon-cote-dor","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/","title":{"rendered":"Histoire de Buffon (C\u00f4te d&rsquo;Or)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-41975\" src=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg\" alt=\"\" width=\"280\" height=\"187\" srcset=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg 280w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21-160x107.jpg 160w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/>Buffon tire son nom de \u00ab\u00a0bis fon\u00a0\u00bb qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l&rsquo;\u00e9mergence d&rsquo;eau d&rsquo;infiltration).<\/p>\n<p>En\u00a0<a title=\"1717\" href=\"https:\/\/fr.wikipedia.org\/wiki\/1717\">1717<\/a>, Benjamin Leclerc (p\u00e8re du naturaliste) ach\u00e8te la seigneurie de Buffon \u00e0\u00a0<a class=\"mw-redirect\" title=\"\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Jean_Bouhier_(juriste_et_%C3%A9crivain)\">Jean Bouhier<\/a>\u00a0gr\u00e2ce \u00e0 la fortune h\u00e9rit\u00e9e de Georges-Louis Blaisot, collecteur des imp\u00f4ts du\u00a0<a class=\"mw-redirect\" title=\"Duc de Savoie\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Duc_de_Savoie\">duc de Savoie<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buffon tire son nom de \u00ab\u00a0bis fon\u00a0\u00bb qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l&rsquo;\u00e9mergence d&rsquo;eau d&rsquo;infiltration). En\u00a01717, Benjamin Leclerc (p\u00e8re du naturaliste) ach\u00e8te la seigneurie de Buffon \u00e0\u00a0Jean Bouhier\u00a0gr\u00e2ce \u00e0 la fortune h\u00e9rit\u00e9e de Georges-Louis &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":41975,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[67],"wpbdp_tag":[],"class_list":["post-41974","wpbdp_listing","type-wpbdp_listing","status-publish","has-post-thumbnail","hentry","wpbdp_category-21-cote-dor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Buffon (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"description\" content=\"Buffon tire son nom de &quot;bis fon&quot; qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l&#039;\u00e9mergence d&#039;eau d&#039;infiltration).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Buffon (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"Buffon tire son nom de &quot;bis fon&quot; qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l&#039;\u00e9mergence d&#039;eau d&#039;infiltration).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"og:image\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/\",\"name\":\"Histoire de Buffon (C\u00f4te d'Or) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/buffon21.jpg\",\"datePublished\":\"2022-01-27T13:00:39+00:00\",\"description\":\"Buffon tire son nom de \\\"bis fon\\\" qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l'\u00e9mergence d'eau d'infiltration).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/buffon21.jpg\",\"contentUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/buffon21.jpg\",\"width\":280,\"height\":187},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-buffon-cote-dor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Buffon (C\u00f4te d&rsquo;Or)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Buffon (C\u00f4te d'Or) - Annuaire Historique des Communes de France","description":"Buffon tire son nom de \"bis fon\" qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l'\u00e9mergence d'eau d'infiltration).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Buffon (C\u00f4te d'Or) - Annuaire Historique des Communes de France","og_description":"Buffon tire son nom de \"bis fon\" qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l'\u00e9mergence d'eau d'infiltration).","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","og_image":[{"url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/","name":"Histoire de Buffon (C\u00f4te d'Or) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/#primaryimage"},"image":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/#primaryimage"},"thumbnailUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg","datePublished":"2022-01-27T13:00:39+00:00","description":"Buffon tire son nom de \"bis fon\" qui signifie deux fontaines (la situation g\u00e9ologique est effectivement propice \u00e0 l'\u00e9mergence d'eau d'infiltration).","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/#primaryimage","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg","contentUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/01\/buffon21.jpg","width":280,"height":187},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-buffon-cote-dor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire de Buffon (C\u00f4te d&rsquo;Or)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/41974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=41974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media\/41975"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=41974"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=41974"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=41974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}