{"id":45666,"date":"2022-11-07T13:26:20","date_gmt":"2022-11-07T12:26:20","guid":{"rendered":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?post_type=wpbdp_listing&#038;p=45666"},"modified":"2022-11-07T13:26:20","modified_gmt":"2022-11-07T12:26:20","slug":"histoire-de-planay-cote-dor","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/","title":{"rendered":"Histoire de Planay (C\u00f4te d&rsquo;Or)"},"content":{"rendered":"<p>Histoire de Planay (C\u00f4te d&rsquo;Or)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-45667\" src=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21-300x169.jpg 300w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21-160x90.jpg 160w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21.jpg 420w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.<br \/>\nLes habitants sont affranchis en 1527.<br \/>\nEn 1838, l\u2019\u00e9levage du ver \u00e0 soie devient une particularit\u00e9 de Planay. 20 000 muriers sont plant\u00e9s sur 4 hectares. ..<\/p>\n<p>(source wikipedia&#8230; lire la suite)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire de Planay (C\u00f4te d&rsquo;Or) \u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay. Les habitants sont affranchis en 1527. En 1838, l\u2019\u00e9levage du ver \u00e0 soie devient une particularit\u00e9 de Planay. 20 000 muriers sont plant\u00e9s sur &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":45667,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[67],"wpbdp_tag":[],"class_list":["post-45666","wpbdp_listing","type-wpbdp_listing","status-publish","has-post-thumbnail","hentry","wpbdp_category-21-cote-dor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire de Planay (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"description\" content=\"\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.Les habitants sont affranchis en 1527.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire de Planay (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.Les habitants sont affranchis en 1527.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"og:image\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/\",\"name\":\"Histoire de Planay (C\u00f4te d'Or) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/planay21.jpg\",\"datePublished\":\"2022-11-07T12:26:20+00:00\",\"description\":\"\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.Les habitants sont affranchis en 1527.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/planay21.jpg\",\"contentUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/planay21.jpg\",\"width\":420,\"height\":236},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-de-planay-cote-dor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire de Planay (C\u00f4te d&#8217;Or)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire de Planay (C\u00f4te d'Or) - Annuaire Historique des Communes de France","description":"\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.Les habitants sont affranchis en 1527.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire de Planay (C\u00f4te d'Or) - Annuaire Historique des Communes de France","og_description":"\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.Les habitants sont affranchis en 1527.","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","og_image":[{"width":420,"height":236,"url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/","name":"Histoire de Planay (C\u00f4te d'Or) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/#primaryimage"},"image":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/#primaryimage"},"thumbnailUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21.jpg","datePublished":"2022-11-07T12:26:20+00:00","description":"\u00c0 l\u2019origine, le village \u00e9tait une grange de l\u2019abbaye de Fontenay.Les habitants sont affranchis en 1527.","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/#primaryimage","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21.jpg","contentUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/11\/planay21.jpg","width":420,"height":236},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-de-planay-cote-dor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire de Planay (C\u00f4te d&#8217;Or)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/45666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=45666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media\/45667"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=45666"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=45666"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=45666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}