{"id":46257,"date":"2022-12-22T11:32:59","date_gmt":"2022-12-22T10:32:59","guid":{"rendered":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?post_type=wpbdp_listing&#038;p=46257"},"modified":"2022-12-22T11:32:59","modified_gmt":"2022-12-22T10:32:59","slug":"histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor","status":"publish","type":"wpbdp_listing","link":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/","title":{"rendered":"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&rsquo;Or)"},"content":{"rendered":"<p>Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&rsquo;Or)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-46258\" src=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21-218x300.jpg\" alt=\"\" width=\"218\" height=\"300\" srcset=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21-218x300.jpg 218w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21-703x968.jpg 703w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21-160x220.jpg 160w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21-509x700.jpg 509w, https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21.jpg 744w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/>Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus. A l&rsquo;\u00e9poque celte, Saint-Marc passait pour un grand centre druidique. Les druides se rassemblaient \u00e0 la Roche Fodru, qui \u00e9tait une grande roche isol\u00e9e formant une table et que certains consid\u00e9raient comme un dolmen, et \u00e0 la Roche Madame qui pouvait \u00eatre hant\u00e9e par une f\u00e9e&#8230;.<\/p>\n<p>(image et extrait du site officiel de la commune&#8230; lire la suite)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&rsquo;Or) Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus. A l&rsquo;\u00e9poque celte, Saint-Marc passait pour un grand centre druidique. Les druides se rassemblaient \u00e0 la Roche &hellip; <a href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":46258,"comment_status":"open","ping_status":"closed","template":"","meta":[],"wpbdp_category":[67],"wpbdp_tag":[],"class_list":["post-46257","wpbdp_listing","type-wpbdp_listing","status-publish","has-post-thumbnail","hentry","wpbdp_category-21-cote-dor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France<\/title>\n<meta name=\"description\" content=\"Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&#039;Or) - Annuaire Historique des Communes de France\" \/>\n<meta property=\"og:description\" content=\"Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/\" \/>\n<meta property=\"og:site_name\" content=\"Annuaire Historique des Communes de France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sites.HistoiredeFrance\" \/>\n<meta property=\"og:image\" content=\"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"744\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/\",\"name\":\"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d'Or) - Annuaire Historique des Communes de France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/saintmarcsurseine21.jpg\",\"datePublished\":\"2022-12-22T10:32:59+00:00\",\"description\":\"Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/saintmarcsurseine21.jpg\",\"contentUrl\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/saintmarcsurseine21.jpg\",\"width\":744,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/annuaire-professionnel\\\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&#8217;Or)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#website\",\"url\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/\",\"name\":\"Annuaire Historique des Communes de France\",\"description\":\"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France\",\"publisher\":{\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/charles-de-flahaut.fr\\\/annuaire-histoire-communes\\\/#\\\/schema\\\/person\\\/d16946e994227e7154f6f213ea03ae7b\",\"name\":\"administrateur2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\",\"caption\":\"administrateur2\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sites.HistoiredeFrance\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d'Or) - Annuaire Historique des Communes de France","description":"Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/","og_locale":"fr_FR","og_type":"article","og_title":"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d'Or) - Annuaire Historique des Communes de France","og_description":"Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus.","og_url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/","og_site_name":"Annuaire Historique des Communes de France","article_publisher":"https:\/\/www.facebook.com\/Sites.HistoiredeFrance","og_image":[{"width":744,"height":1024,"url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/","name":"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d'Or) - Annuaire Historique des Communes de France","isPartOf":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/#primaryimage"},"image":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/#primaryimage"},"thumbnailUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21.jpg","datePublished":"2022-12-22T10:32:59+00:00","description":"Saint-Marc-sur-Seine est mentionn\u00e9 pour la premi\u00e8re fois en 992 sous la forme Sanctus Medadus.","breadcrumb":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/#primaryimage","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21.jpg","contentUrl":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-content\/uploads\/2022\/12\/saintmarcsurseine21.jpg","width":744,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/annuaire-professionnel\/histoire-et-patrimoine-de-saint-marc-sur-seine-cote-dor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/"},{"@type":"ListItem","position":2,"name":"Histoire et patrimoine de Saint-Marc sur Seine (C\u00f4te d&#8217;Or)"}]},{"@type":"WebSite","@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#website","url":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/","name":"Annuaire Historique des Communes de France","description":"annuaire recensant les pages relatives \u00e0 l&#039;Histoire et au Patrimoine des villes et villages de France","publisher":{"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/#\/schema\/person\/d16946e994227e7154f6f213ea03ae7b","name":"administrateur2","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g","caption":"administrateur2"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d0fc7d68e15c7c456cf6f1b9b774d54a7a9e6452d8deac23b3f1ef133710d3d3?s=96&d=mm&r=g"},"sameAs":["https:\/\/www.facebook.com\/Sites.HistoiredeFrance"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing\/46257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_listing"}],"about":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/types\/wpbdp_listing"}],"author":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/comments?post=46257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media\/46258"}],"wp:attachment":[{"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/media?parent=46257"}],"wp:term":[{"taxonomy":"wpbdp_category","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_category?post=46257"},{"taxonomy":"wpbdp_tag","embeddable":true,"href":"https:\/\/charles-de-flahaut.fr\/annuaire-histoire-communes\/wp-json\/wp\/v2\/wpbdp_tag?post=46257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}